{"id":4028,"date":"2021-09-13T15:59:39","date_gmt":"2021-09-13T13:59:39","guid":{"rendered":"https:\/\/eticasfoundation.org\/https-eticasfoundation-org-algorithms-es-case-parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/"},"modified":"2021-09-14T15:00:26","modified_gmt":"2021-09-14T13:00:26","slug":"parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa","status":"publish","type":"post","link":"https:\/\/dev.eticasfoundation.org\/es\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/","title":{"rendered":"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa"},"content":{"rendered":"<p>La herramienta de admisi\u00f3n algor\u00edtmica francesa &#8216;Parcoursup&#8217; fue noticia en 2018 cuando rechaz\u00f3 a futuros estudiantes de universidades p\u00fablicas (AlgorithmWatch, 2019). Mientras que antes cualquier solicitante con un diploma de escuela secundaria ten\u00eda derecho a inscribirse, Parcoursup, seg\u00fan los informes, aconsej\u00f3 a las universidades francesas que rechazaran y admitieran estudiantes en base a criterios de selecci\u00f3n opacos (ibid). El gobierno franc\u00e9s no notific\u00f3 a los usuarios que su rechazo fue producto de la toma de decisiones algor\u00edtmicas, pero s\u00ed public\u00f3 el c\u00f3digo fuente que hac\u00eda la selecci\u00f3n correspondiente. El software supuestamente produce sus decisiones a partir del procesamiento de datos personales e informaci\u00f3n del solicitante (ibid).<\/p>","protected":false},"excerpt":{"rendered":"<p>La herramienta de admisi\u00f3n algor\u00edtmica francesa &#8216;Parcoursup&#8217; fue noticia en 2018 cuando rechaz\u00f3 a futuros estudiantes de universidades p\u00fablicas (AlgorithmWatch, 2019). Mientras que antes cualquier solicitante con un diploma de escuela secundaria ten\u00eda derecho a inscribirse, Parcoursup, seg\u00fan los informes, aconsej\u00f3 a las universidades francesas que rechazaran y admitieran estudiantes en base a criterios de [&hellip;]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa - Eticas Foundation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.eticasfoundation.org\/es\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa - Eticas Foundation\" \/>\n<meta property=\"og:description\" content=\"La herramienta de admisi\u00f3n algor\u00edtmica francesa &#8216;Parcoursup&#8217; fue noticia en 2018 cuando rechaz\u00f3 a futuros estudiantes de universidades p\u00fablicas (AlgorithmWatch, 2019). Mientras que antes cualquier solicitante con un diploma de escuela secundaria ten\u00eda derecho a inscribirse, Parcoursup, seg\u00fan los informes, aconsej\u00f3 a las universidades francesas que rechazaran y admitieran estudiantes en base a criterios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.eticasfoundation.org\/es\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Eticas Foundation\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-13T13:59:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-14T13:00:26+00:00\" \/>\n<meta name=\"author\" content=\"Eticas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eticas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\"},\"author\":{\"name\":\"Eticas\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/#\/schema\/person\/c522dcf4e56cf946a9c1e8a1697cf980\"},\"headline\":\"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa\",\"datePublished\":\"2021-09-13T13:59:39+00:00\",\"dateModified\":\"2021-09-14T13:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\"},\"wordCount\":128,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/#organization\"},\"articleSection\":[\"Algorithms\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\",\"url\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\",\"name\":\"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa - Eticas Foundation\",\"isPartOf\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/#website\"},\"datePublished\":\"2021-09-13T13:59:39+00:00\",\"dateModified\":\"2021-09-14T13:00:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.eticasfoundation.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/#website\",\"url\":\"https:\/\/dev.eticasfoundation.org\/\",\"name\":\"Eticas Foundation\",\"description\":\"Society \u00b7 Technology \u00b7 Responsibility\",\"publisher\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.eticasfoundation.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/#organization\",\"name\":\"Eticas Foundation\",\"url\":\"https:\/\/dev.eticasfoundation.org\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eticasfoundation.org\/wp-content\/uploads\/2020\/04\/eticas-foundation-logo-grande.png\",\"contentUrl\":\"https:\/\/eticasfoundation.org\/wp-content\/uploads\/2020\/04\/eticas-foundation-logo-grande.png\",\"width\":750,\"height\":400,\"caption\":\"Eticas Foundation\"},\"image\":{\"@id\":\"https:\/\/dev.eticasfoundation.org\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/#\/schema\/person\/c522dcf4e56cf946a9c1e8a1697cf980\",\"name\":\"Eticas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev.eticasfoundation.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b324aea2090dd32817be50f33807f8e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b324aea2090dd32817be50f33807f8e4?s=96&d=mm&r=g\",\"caption\":\"Eticas\"},\"url\":\"https:\/\/dev.eticasfoundation.org\/es\/author\/eticas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa - Eticas Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.eticasfoundation.org\/es\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/","og_locale":"es_ES","og_type":"article","og_title":"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa - Eticas Foundation","og_description":"La herramienta de admisi\u00f3n algor\u00edtmica francesa &#8216;Parcoursup&#8217; fue noticia en 2018 cuando rechaz\u00f3 a futuros estudiantes de universidades p\u00fablicas (AlgorithmWatch, 2019). Mientras que antes cualquier solicitante con un diploma de escuela secundaria ten\u00eda derecho a inscribirse, Parcoursup, seg\u00fan los informes, aconsej\u00f3 a las universidades francesas que rechazaran y admitieran estudiantes en base a criterios de [&hellip;]","og_url":"https:\/\/dev.eticasfoundation.org\/es\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/","og_site_name":"Eticas Foundation","article_published_time":"2021-09-13T13:59:39+00:00","article_modified_time":"2021-09-14T13:00:26+00:00","author":"Eticas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eticas","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#article","isPartOf":{"@id":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/"},"author":{"name":"Eticas","@id":"https:\/\/dev.eticasfoundation.org\/#\/schema\/person\/c522dcf4e56cf946a9c1e8a1697cf980"},"headline":"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa","datePublished":"2021-09-13T13:59:39+00:00","dateModified":"2021-09-14T13:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/"},"wordCount":128,"commentCount":0,"publisher":{"@id":"https:\/\/dev.eticasfoundation.org\/#organization"},"articleSection":["Algorithms"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/","url":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/","name":"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa - Eticas Foundation","isPartOf":{"@id":"https:\/\/dev.eticasfoundation.org\/#website"},"datePublished":"2021-09-13T13:59:39+00:00","dateModified":"2021-09-14T13:00:26+00:00","breadcrumb":{"@id":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.eticasfoundation.org\/parcoursup-algoritmo-de-seleccion-de-admision-a-la-universidad-francesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.eticasfoundation.org\/"},{"@type":"ListItem","position":2,"name":"Parcoursup: algoritmo de selecci\u00f3n de admisi\u00f3n a la universidad francesa"}]},{"@type":"WebSite","@id":"https:\/\/dev.eticasfoundation.org\/#website","url":"https:\/\/dev.eticasfoundation.org\/","name":"Eticas Foundation","description":"Society \u00b7 Technology \u00b7 Responsibility","publisher":{"@id":"https:\/\/dev.eticasfoundation.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.eticasfoundation.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dev.eticasfoundation.org\/#organization","name":"Eticas Foundation","url":"https:\/\/dev.eticasfoundation.org\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev.eticasfoundation.org\/#\/schema\/logo\/image\/","url":"https:\/\/eticasfoundation.org\/wp-content\/uploads\/2020\/04\/eticas-foundation-logo-grande.png","contentUrl":"https:\/\/eticasfoundation.org\/wp-content\/uploads\/2020\/04\/eticas-foundation-logo-grande.png","width":750,"height":400,"caption":"Eticas Foundation"},"image":{"@id":"https:\/\/dev.eticasfoundation.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.eticasfoundation.org\/#\/schema\/person\/c522dcf4e56cf946a9c1e8a1697cf980","name":"Eticas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev.eticasfoundation.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b324aea2090dd32817be50f33807f8e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b324aea2090dd32817be50f33807f8e4?s=96&d=mm&r=g","caption":"Eticas"},"url":"https:\/\/dev.eticasfoundation.org\/es\/author\/eticas\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/posts\/4028"}],"collection":[{"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/comments?post=4028"}],"version-history":[{"count":1,"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/posts\/4028\/revisions"}],"predecessor-version":[{"id":4052,"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/posts\/4028\/revisions\/4052"}],"wp:attachment":[{"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/media?parent=4028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/categories?post=4028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.eticasfoundation.org\/es\/wp-json\/wp\/v2\/tags?post=4028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}